{"id":11122,"date":"2026-08-08T08:44:27","date_gmt":"2026-08-08T12:44:27","guid":{"rendered":"https:\/\/gillesenvrac.ca\/carnet\/?p=11122"},"modified":"2026-08-17T07:50:50","modified_gmt":"2026-08-17T11:50:50","slug":"complementarites","status":"publish","type":"post","link":"https:\/\/gillesenvrac.ca\/carnet\/2026\/08\/complementarites\/","title":{"rendered":"compl\u00e9mentarit\u00e9s : trois panels et une conf\u00e9renci\u00e8re"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Trois panels et une conf\u00e9rence \u00ab\u00a0tenus \u00ab\u00a0keynote\u00a0\u00bb qui se sont tenus \u00e0 Amsterdam en juin dernier autour du th\u00e8me \u00ab\u00a0Technologie et d\u00e9mocratie\u00a0\u00bb. Le lancement d&rsquo;une \u00ab\u00a0pile sociale\u00a0\u00bb europ\u00e9enne, avec l&rsquo;appui des grands de l&rsquo;<em>Open source<\/em> (qui sont souvent plus concurrents que collaborateurs) : sera-ce plus qu&rsquo;une d\u00e9claration ? ; une discussion autour des relations entre m\u00e9dias traditionnels et r\u00e9seaux sociaux : comment les grands m\u00e9dias (et leurs journalistes) peuvent-ils regagner la confiance de leurs publics ? Le projet d&rsquo;incubateur d&rsquo;espaces publics voudrait les aider; des leaders d&rsquo;initiatives (dont le fondateur de Blacksky) bas\u00e9es sur l&rsquo;Open social web (ATproto et ActivityPub) pr\u00e9sentent leurs perspectives de d\u00e9veloppement. <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Ce panel tenu lors du <a href=\"https:\/\/conference.publicspaces.net\/en\">PublicSpaces Conference 2026 : Technology for Democracy<\/a>, pr\u00e9sentait la d\u00e9claration sign\u00e9e par les grands de l&rsquo;Open : <a href=\"https:\/\/european.social\/\">The European Social Stack<\/a>.<sup id=\"mfn-content-000000000000083f0000000000000000_11122-1\" class=\"modern-footnotes-footnote modern-footnotes-footnote--hover-on-desktop \" data-mfn=\"1\" data-mfn-post-scope=\"000000000000083f0000000000000000_11122\"><a href=\"javascript:void(0)\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-000000000000083f0000000000000000_11122-1\">1<\/a><\/sup><span role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"1\">[Voir <a href=\"https:\/\/gillesenvrac.ca\/carnet\/la-pile-sociale-europeenne\/\">La pile sociale europ\u00e9enne<\/a>.]<\/span> <\/p>\n\n\n\n<!--more-->\n\n\n\n<iframe frameborder=\"0\" src=\"https:\/\/video.publicspaces.net\/videos\/embed\/o1khpHT11nDkBmSEcmxuJa\" class=\"\" style=\"width:100%;max-width:100%;height:320px\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/european.social\">https:\/\/european.social<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"856\" src=\"https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/ESStack-1200x856.png\" alt=\"\" class=\"wp-image-11123\" style=\"aspect-ratio:1.401878901948597;width:389px;height:auto\" srcset=\"https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/ESStack-1200x856.png 1200w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/ESStack-744x531.png 744w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/ESStack-420x300.png 420w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/ESStack-768x548.png 768w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/ESStack.png 1424w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Extrait de <a href=\"https:\/\/european.social\/\">la d\u00e9claration <\/a>(<a href=\"https:\/\/gillesenvrac.ca\/carnet\/la-pile-sociale-europeenne\/\">La pile sociale europ\u00e9enne<\/a>) : <\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-small-font-size\">Trois couches compl\u00e9mentaires.<\/h2>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Les technologies en r\u00e9seau forment des structures qui permettent de r\u00e9pondre \u00e0 diff\u00e9rents besoins de gouvernance selon les contextes. La combinaison de ces trois couches couvre un large \u00e9ventail de domaines :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">La messagerie priv\u00e9e<\/li>\n\n\n\n<li class=\"has-small-font-size\">Le Fediverse<\/li>\n\n\n\n<li class=\"has-small-font-size\">L\u2019Atmosphere<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Pour la messagerie priv\u00e9e en groupe, les normes ouvertes (comme Matrix ou XMPP) sont id\u00e9ales pour la communication instantan\u00e9e ou le partage entre proches. Plusieurs \u00c9tats membres de l\u2019UE ont adopt\u00e9 avec succ\u00e8s ces protocoles, notamment pour des applications li\u00e9es \u00e0 la s\u00e9curit\u00e9 et \u00e0 la d\u00e9fense.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Le Fediverse, articul\u00e9 autour d\u2019ActivityPub, s\u2019est d\u00e9velopp\u00e9 \u00e0 partir de communaut\u00e9s locales soud\u00e9es qui interagissent entre elles, et relie tous les aspects d\u2019une plateforme sociale ou d\u2019une publication num\u00e9rique au sein d\u2019un d\u00e9ploiement unique. Mastodon, PeerTube et Mobilizon en sont des exemples.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Atmosphere, qui utilise AT, trouve ses fondements dans les syst\u00e8mes de m\u00e9dias sociaux publics \u00e0 grande \u00e9chelle et offre, en cons\u00e9quence, le type de gouvernance d\u00e9centralis\u00e9e que l\u2019on est en droit d\u2019attendre de grands syst\u00e8mes d\u00e9mocratiques. On peut l\u2019observer \u00e0 l\u2019\u0153uvre dans Eurosky, Flashes, Tangled ou le plus r\u00e9cent Web Tiles.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"314\" src=\"https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Founding-ESStack-1200x314.png\" alt=\"\" class=\"wp-image-11124\" srcset=\"https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Founding-ESStack-1200x314.png 1200w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Founding-ESStack-744x195.png 744w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Founding-ESStack-420x110.png 420w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Founding-ESStack-768x201.png 768w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Founding-ESStack-1536x402.png 1536w, https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Founding-ESStack-2048x535.png 2048w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Extraits de <a href=\"https:\/\/gillesenvrac.ca\/carnet\/la-pile-sociale-europeenne\/\">La pile sociale europ\u00e9enne<\/a> : \u00ab\u00a0nous construisons le Web social comme une couche essentielle d\u2019une Europe ind\u00e9pendante.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Les r\u00e9seaux sociaux d\u00e9centralis\u00e9s correspondent au mod\u00e8le europ\u00e9en : diversit\u00e9 et autonomie locale reli\u00e9es par des normes transparentes et ouvertes pour former un tout robuste et r\u00e9silient. En tant qu\u2019Europ\u00e9ens, nous saisissons l\u2019occasion de passer \u00e0 des r\u00e9seaux sociaux et \u00e0 des protocoles r\u00e9silients et d\u00e9centralis\u00e9s, loin des \u00ab jardins clos \u00bb d\u00e9tenus par des oligarques.\u00a0\u00bb <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais les instances Mastodon ou Matrix ne sont-ils pas, par d\u00e9finition, des \u00ab\u00a0jardins clos\u00a0\u00bb ? <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-peertube wp-block-embed-peertube\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/video.publicspaces.net\/w\/6yJgpJn3YPcaKjiN9tqLGt\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un autre panel lors de cette m\u00eame conf\u00e9rence de juin <strong>Social media, Journalism &amp; Democracy @ PublicSpaces Conference 2026<\/strong>. Avec Catherine Tait notamment pour pr\u00e9senter le projet Public Spaces Incubator dont <a href=\"https:\/\/gillesenvrac.ca\/carnet\/at-ap-ec\/incubateur-espaces-publics\/\">j&rsquo;ai parl\u00e9 ici.<\/a> Quelques notes prises durant l&rsquo;\u00e9coute :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Les journalistes doivent r\u00e9apprendre \u00e0 sortir et aller \u00e0 la rencontre de leur public, \u00e9couter leur public&#8230; Comment ferons-nous pour construire, reconstruire le nouveau m\u00e9dia social (European social stack, PSI&#8230;) en y apportant les valeurs qui ont \u00e9t\u00e9 \u00e0 l&rsquo;origine des m\u00e9dia publics de l&rsquo;apr\u00e8s-guerre : d\u00e9mocratie, responsabilit\u00e9, justice&#8230; Lorsque nous allons vers le public, non pas pour cr\u00e9er un nouveau Twitter mais pour construire AVEC EUX ce dont ils ont besoin. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;\u00c0 ceux qui disent que c&rsquo;est impossible de remplacer les m\u00e9dias sociaux actuels, qui sont trop puissants, je dis que nous avons encore une bonne position \u00e0 partir de laquelle travailler : la puissance des m\u00e9dias traditionnels, la confiance qu&rsquo;ils inspirent encore&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Comment aller vers le public, pour construire, renforcer la confiance mutuelle, tout en prot\u00e9geant les journalistes, en particulier les femmes journalistes, qui font du journalisme d&rsquo;investigation et sont confront\u00e9.e.s \u00e0 de l&rsquo;agressivit\u00e9, de la violence ? Les patrons doivent \u00eatre form\u00e9s pour mieux comprendre les dangers d&rsquo;aujourd&rsquo;hui&#8230; et l&rsquo;industrie, la profession doit agir \u00e0 l&rsquo;\u00e9chelle collective car beaucoup des journalistes aujourd&rsquo;hui sont \u00ab\u00a0freelance\u00a0\u00bb, sans attache organisationnelle et, donc, sans protection d&rsquo;une organisation.&nbsp;\u00bb<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Et ce troisi\u00e8me panel : <strong>Growth and Sustainability of the Open Social Web @ PublicSpaces Conference 2026<\/strong>, avec des repr\u00e9sentants des grands r\u00e9seaux ouverts : la COO de Bluesky, <strong>Rose Wang<\/strong>, le fondateur de Blacksky, <strong>Rudy Fraser<\/strong>, un co-leader de Eurosky, <strong>Sebastian Vogelsang<\/strong> et le co-fondateur de Mastodon Inc, l&rsquo;entit\u00e9 \u00ab\u00a0non-profit\u00a0\u00bb responsable du d\u00e9ploiement de Mastodon aux USA, <strong>Felix Hlatky<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-peertube wp-block-embed-peertube\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/video.publicspaces.net\/w\/viCXYbYvkwrMaDF9EaZnsr\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;\u00e9tait int\u00e9ressant d&rsquo;entendre ces leaders exp\u00e9riment\u00e9s \u00e9changer sur les enjeux de soutenabilit\u00e9, de financement, mais aussi \u00e0 propos des perspectives de d\u00e9veloppement qu&rsquo;ils entrevoient, bas\u00e9es sur les chemins d\u00e9j\u00e0 parcourus. <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">En fouillant dans les compte-rendus des deux \u00e9v\u00e9nements, je me rends compte que la m\u00eame personne, <strong>Erin Kissane<\/strong>, a livr\u00e9 une pr\u00e9sentation \u00ab\u00a0keynote\u00a0\u00bb \u00e0 la rencontre \u00ab\u00a0Atmosph\u00e8re\u00a0\u00bb de mars \u00e0 Vancouver ET \u00e0 celle du PublicSpaces \u00e0 Amsterdam de juin. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je crois que c&rsquo;est Laurens Hof qui m&rsquo;a orient\u00e9 vers Kissane, dans son billet <a href=\"https:\/\/gillesenvrac.ca\/carnet\/reflexions-hof-sur-atmosphereconf\/\">R\u00e9flexions sur AtmosphereConf<\/a> publi\u00e9 le 3 avril dernier. Apr\u00e8s ses mots \u00e9logieux \u00e0 son endroit (<em>l\u2019une des penseuses les plus perspicaces qui se penchent sur la question de l\u2019impact r\u00e9el de notre infrastructure num\u00e9rique sur nous<\/em>) j&rsquo;ai voulu en savoir un peu plus&#8230; ce qui m&rsquo;a amen\u00e9 \u00e0 son prochain projet : <a href=\"https:\/\/www.wrecka.ge\/launching-a-cloud-atlas\/\">Launching a Cloud Atlas<\/a> sur son site <a href=\"https:\/\/www.wrecka.ge\">wreckage\/salvage<\/a>. J&rsquo;ai vraiment appr\u00e9ci\u00e9 le style de Kissane, plus qu&rsquo;un style, c&rsquo;est un m\u00e9lange de savoirs scientifiques et d&rsquo;approche po\u00e9tique\/nature&#8230; j&rsquo;ai traduit cet article du 29 juillet : <a href=\"https:\/\/gillesenvrac.ca\/carnet\/un-atlas-du-cloud-kissane\/\">Lancer un \u00ab Atlas du Cloud \u00bb<\/a>. Vous me direz ce que vous en pensez&#8230; de son style. Ce projet, par ailleurs, me semble des plus pertinents, consid\u00e9rant la diversit\u00e9 confinant au chaos caract\u00e9risant les d\u00e9veloppements rapides des mondes du fediverse et atmosphere. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est alors que j&rsquo;ai d\u00e9couvert que Kissane \u00e9tait aussi \u00e0 la conf\u00e9rence d&rsquo;Amsterdam ! Alors l\u00e0 je l&rsquo;ai \u00e9cout\u00e9e. Je crois que c&rsquo;est, en gros, le m\u00eame sujet que <a href=\"https:\/\/atmosphereconf.org\/event\/gDELD0M\">celui abord\u00e9 en mars<\/a>. Je vais peut-\u00eatre traduire la transcription de cette derni\u00e8re conf\u00e9rence, pour ceux-celles qui pr\u00e9f\u00e8rent l&rsquo;\u00e9crit \u00e0 l&rsquo;\u00e9coute d&rsquo;une vid\u00e9o d&rsquo;une heure. Mais si vous avez quelques minutes, voici donc la prestation de juin dernier Holdfast. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-peertube wp-block-embed-peertube\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/video.publicspaces.net\/w\/n5NbByWApkACFHYTb6uQF6\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Conf\u00e9rence qui, incidemment, m&rsquo;a fait conna\u00eetre Lisa Herzog auteure de ce livre <a href=\"https:\/\/academic.oup.com\/book\/46849\">Citizen Knowledge: Markets, Experts, and the Infrastructure of Democracy<\/a> disponible en acc\u00e8s-libre. Cec document de plus de 300 pages&#8230; je n&rsquo;ai pu le traduire en bloc, il d\u00e9passait les limites de mon forfait aupr\u00e8s de DeepL. Mais en le d\u00e9coupant, j&rsquo;ai pu en (faire) traduire la premi\u00e8re partie que voici. Je pourrai, \u00e9ventuellement, traduire les deux autres parties. <\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">\u00c0 NOTER : cette traduction r\u00e9alis\u00e9e avec DeepL n&rsquo;a pas \u00e9t\u00e9 relue, aussi il est bien possible que les phrases qui commencent \u00e0 la fin d&rsquo;une page pour se poursuivre \u00e0 la page suivante soient \u00ab\u00a0d\u00e9faillantes\u00a0\u00bb parfois. C&rsquo;est ce que mon exp\u00e9rience m&rsquo;a appris du traitement des PDF par ce moteur de traduction. Je la d\u00e9pose ici pour ma propre gouverne et votre service si, comme moi, vous aviez l&rsquo;intention de jeter un oeil, ou m\u00eame de lire au complet ce document. <\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Citizen_1_Herzog_fr.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Citizen_1_Herzog_fr.\"><\/object><a id=\"wp-block-file--media-1ef3e82d-9336-4d65-9f7d-b4d3181f175e\" href=\"https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Citizen_1_Herzog_fr.pdf\">Citizen_1_Herzog_fr<\/a><a href=\"https:\/\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/08\/Citizen_1_Herzog_fr.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1ef3e82d-9336-4d65-9f7d-b4d3181f175e\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<h3 class=\"modern-footnotes-list-heading \">Notes <\/h3><ul class=\"modern-footnotes-list \"><li id=\"footnote-000000000000083f0000000000000000_11122-1\"><span>1<\/span><div>[Voir <a href=\"https:\/\/gillesenvrac.ca\/carnet\/la-pile-sociale-europeenne\/\">La pile sociale europ\u00e9enne<\/a>.] <a href=\"#mfn-content-000000000000083f0000000000000000_11122-1\" class=\"modern-footnotes-scroll-to-footnote\" aria-label=\"Back to reference 1 in text\">\u21a9\ufe0e<\/a><\/div><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Trois panels et une conf\u00e9rence \u00ab\u00a0tenus \u00ab\u00a0keynote\u00a0\u00bb qui se sont tenus \u00e0 Amsterdam en juin dernier autour du th\u00e8me \u00ab\u00a0Technologie et d\u00e9mocratie\u00a0\u00bb. Le lancement d&rsquo;une \u00ab\u00a0pile sociale\u00a0\u00bb europ\u00e9enne, avec l&rsquo;appui des grands de l&rsquo;Open source (qui sont souvent plus concurrents que collaborateurs) : sera-ce plus qu&rsquo;une d\u00e9claration ? ; une discussion autour des relations entre &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gillesenvrac.ca\/carnet\/2026\/08\/complementarites\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;compl\u00e9mentarit\u00e9s : trois panels et une conf\u00e9renci\u00e8re&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"atmosphere_disabled":false,"atmosphere_custom_text":"","atmosphere_reply_restriction":[],"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-11122","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack-related-posts":[{"id":11116,"url":"https:\/\/gillesenvrac.ca\/carnet\/2026\/07\/espaces-publics-protocoles-et-communication\/","url_meta":{"origin":11122,"position":0},"title":"espaces publics, protocoles et communication","author":"Gilles Beauchamp","date":"31 juillet 2026","format":false,"excerpt":"D\u00e9j\u00e0 la fin juillet... comme le temps passe vite. L'an dernier, \u00e0 pareille date (\u00e9t\u00e9 2025), j'\u00e9tais en pleine chroniques habermassiennes : tomb\u00e9 sur deux revues qui avaient chacune publi\u00e9 un num\u00e9ro sp\u00e9cial autour du concept d'espace public de Habermas, j'ai pris le temps de lire la vingtaine d'articles apr\u00e8s\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/07\/opensourceATAPEC.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/07\/opensourceATAPEC.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/07\/opensourceATAPEC.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2026\/07\/opensourceATAPEC.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5439,"url":"https:\/\/gillesenvrac.ca\/carnet\/2016\/02\/esfs\/","url_meta":{"origin":11122,"position":1},"title":"\u00e9conomie sociale et finance solidaire","author":"Gilles Beauchamp","date":"9 f\u00e9vrier 2016","format":"aside","excerpt":"Les conf\u00e9rences du Symposium qui avait lieu jeudi dernier (dont j'ai parl\u00e9 ici) sont maintenant en ligne sur le site WebTV.coop (voir le flux \u00c9conomie solidaire). Je reproduis ici\u00a0le premier panel avec MM Larose, L\u00e9vesque et Boucher, sur le th\u00e8me Concevoir et co-construire un mod\u00e8le se soci\u00e9t\u00e9 solidaire.","rel":"","context":"Dans \"\u00e9conomie sociale\"","block_context":{"text":"\u00e9conomie sociale","link":"https:\/\/gillesenvrac.ca\/carnet\/tag\/economie-sociale\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8255,"url":"https:\/\/gillesenvrac.ca\/carnet\/2025\/06\/lectures-dete-3\/","url_meta":{"origin":11122,"position":2},"title":"lectures d&rsquo;\u00e9t\u00e9 2025","author":"Gilles Beauchamp","date":"14 juin 2025","format":false,"excerpt":"Des lectures que je me promet de poursuivre ou reprendre au cours des prochaines semaines... Lectures ou visionnements, car il y a quelques conf\u00e9rences et entrevues que je n'ai pu encore \u00e9couter qui sont dans ma liste. Commen\u00e7ons par l\u00e0. https:\/\/youtu.be\/sF6TLJ92amU?si=ahagpZijuwimp5Jh Dominique M\u00e9da, en entrevue avec... Dominique M\u00e9da est une\u2026","rel":"","context":"Article similaire","block_context":{"text":"Article similaire","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/sF6TLJ92amU\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5374,"url":"https:\/\/gillesenvrac.ca\/carnet\/2015\/12\/commun-revolution-et-sociologie\/","url_meta":{"origin":11122,"position":3},"title":"commun, r\u00e9volution et sociologie","author":"Gilles Beauchamp","date":"9 d\u00e9cembre 2015","format":false,"excerpt":"Dans le billet pr\u00e9c\u00e9dent je faisais r\u00e9f\u00e9rence \u00e0 cette\u00a0conf\u00e9rence de Streeck, donn\u00e9e\u00a0\u00e0 l'\u00c9cole des hautes \u00e9tudes en sciences sociales. Incidemment ce panel donnait aussi la parole \u00e0 Thomas Piketty. Deux conf\u00e9rences d'une demi-heure qui valent d'\u00eatre entendues (et aussi, mais dans une moindre mesure\u00a0les deux autres interventions par Carla Hesse,\u2026","rel":"","context":"Dans \"Communs\"","block_context":{"text":"Communs","link":"https:\/\/gillesenvrac.ca\/carnet\/tag\/communs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2021\/08\/Capture-de%CC%81cran-le-2021-08-05-a%CC%80-07.17.35.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2021\/08\/Capture-de%CC%81cran-le-2021-08-05-a%CC%80-07.17.35.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2021\/08\/Capture-de%CC%81cran-le-2021-08-05-a%CC%80-07.17.35.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/gillesenvrac.ca\/carnet\/wp-content\/uploads\/2021\/08\/Capture-de%CC%81cran-le-2021-08-05-a%CC%80-07.17.35.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5826,"url":"https:\/\/gillesenvrac.ca\/carnet\/2018\/02\/intelligence-artificielle\/","url_meta":{"origin":11122,"position":4},"title":"intelligence artificielle et finalit\u00e9s sociales","author":"Gilles Beauchamp","date":"28 f\u00e9vrier 2018","format":false,"excerpt":"La conf\u00e9rence de Yoshua Bengio\u00a0(32 minutes) est sans doute ce qui m'a convaincu de m'inscrire \u00e0 ce colloque \u00ab\u00a0Intelligence artificielle en mission sociale \u00bb. \u00a0En tant que figure de prou (montr\u00e9alaise et internationale) du secteur en forte croissante du Deep Learning j'\u00e9tais curieux de voir ce qu'il avait \u00e0 dire\u2026","rel":"","context":"Dans \"\u00e9thique\"","block_context":{"text":"\u00e9thique","link":"https:\/\/gillesenvrac.ca\/carnet\/tag\/ethique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.gillesenvrac.ca\/carnet\/wp-content\/uploads\/2018\/02\/IAAI-420x280.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5866,"url":"https:\/\/gillesenvrac.ca\/carnet\/2018\/04\/grande-transition\/","url_meta":{"origin":11122,"position":5},"title":"La grande transition : le colloque du 17 au 20 mai","author":"Gilles Beauchamp","date":"27 avril 2018","format":false,"excerpt":"La grande transition, pr\u00e9parer la soci\u00e9t\u00e9 apr\u00e8s le capitalisme. Du 17 au 20 mai \u00e0 Montr\u00e9al, avec, parmi ceux que je connais, Alain Devault, Diane Lamoureux, Christian Laval, Pierre Dardot, Jonathan D. Folco. 120 ateliers, 300 panelistes...Tout \u00e7a pour 60$ : beaucoup d\u2019id\u00e9es au $ !\u00a0 https:\/\/thegreattransition.net\/fr\/accueil\/ Organis\u00e9 par plusieurs\u2026","rel":"","context":"Dans \"transition\"","block_context":{"text":"transition","link":"https:\/\/gillesenvrac.ca\/carnet\/tag\/transition\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/posts\/11122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/comments?post=11122"}],"version-history":[{"count":0,"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/posts\/11122\/revisions"}],"wp:attachment":[{"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/media?parent=11122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/categories?post=11122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gillesenvrac.ca\/carnet\/wp-json\/wp\/v2\/tags?post=11122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}